{"id":92612,"date":"2025-10-27T12:47:42","date_gmt":"2025-10-27T12:47:42","guid":{"rendered":"https:\/\/brandss.com.py\/index\/?post_type=product&#038;p=92612"},"modified":"2025-10-28T18:34:01","modified_gmt":"2025-10-28T18:34:01","slug":"luz-led-koosda-krl-st10-full-screen-10","status":"publish","type":"product","link":"https:\/\/brandss.com.py\/index\/producto\/luz-led-koosda-krl-st10-full-screen-10\/","title":{"rendered":"LUZ LED KOOSDA KRL-ST10 FULL SCREEN 10&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/koosda.com\/uploads\/20250302\/026e881b0915f3857a1788ccdb06bc6a.png\" alt=\"KSD-W02 Magsafe Magnetic Wireless Charger Holder-Wireless Charger-KOOSDA - Premium Mobile Accessories &amp; Live-Streaming Gear for a Smarter Life\" width=\"113\" height=\"30\" \/><\/p>\n<h1>KRL-ST10<\/h1>\n<p data-start=\"327\" data-end=\"815\">Es una luz de relleno LED de pantalla completa de 10 pulgadas, orientada a creadores de contenido, transmisiones en vivo, videoblogs y usos de belleza\/maquillaje. Su dise\u00f1o permite iluminar de forma amplia la escena o al sujeto en lugar de usar una luz puntual peque\u00f1a.<\/p>\n<h3 data-start=\"822\" data-end=\"857\">Caracter\u00edsticas<\/h3>\n<ul data-start=\"895\" data-end=\"1580\">\n<li data-start=\"895\" data-end=\"1022\">\n<p data-start=\"897\" data-end=\"1022\">Tama\u00f1o: 10 pulgadas (aproximadamente) para la cara frontal de la luz (\u201cfull\u2010screen\u201d).<\/p>\n<\/li>\n<li data-start=\"1023\" data-end=\"1207\">\n<p data-start=\"1025\" data-end=\"1207\">Temperatura de color ajustable: rango de 3000K a 6500K .<\/p>\n<\/li>\n<li data-start=\"1208\" data-end=\"1274\">\n<p data-start=\"1210\" data-end=\"1274\">Color del cuerpo: negro.<\/p>\n<\/li>\n<li data-start=\"1275\" data-end=\"1431\">\n<p data-start=\"1277\" data-end=\"1431\">Uso sugerido: \u201cLive Broadcast \/ Beauty Fill Light\u201d \u2014 ideal para streaming, maquillaje, selfies o v\u00eddeo de rostros.<\/p>\n<\/li>\n<li data-start=\"1432\" data-end=\"1580\">\n<p data-start=\"1434\" data-end=\"1580\">Marca: KOOSDA.<\/p>\n<\/li>\n<li data-start=\"1432\" data-end=\"1580\">Modelo: KRL-ST10<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>KRL-ST10 Es una luz de relleno LED de pantalla completa de 10 pulgadas, orientada a creadores de contenido, transmisiones en<\/p>\n","protected":false},"featured_media":92754,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[1087],"product_cat":[89],"product_tag":[1092],"class_list":{"0":"post-92612","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-koosda","7":"product_cat-electronicos","8":"product_tag-1092","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/92612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/comments?post=92612"}],"version-history":[{"count":1,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/92612\/revisions"}],"predecessor-version":[{"id":92613,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/92612\/revisions\/92613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media\/92754"}],"wp:attachment":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media?parent=92612"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_brand?post=92612"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_cat?post=92612"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_tag?post=92612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}