{"id":97739,"date":"2026-02-07T11:32:41","date_gmt":"2026-02-07T11:32:41","guid":{"rendered":"https:\/\/brandss.com.py\/index\/?post_type=product&#038;p=97739"},"modified":"2026-02-07T11:33:00","modified_gmt":"2026-02-07T11:33:00","slug":"shampoo-capilar-kerasys-oriental-premium-intensive-600ml","status":"publish","type":"product","link":"https:\/\/brandss.com.py\/index\/producto\/shampoo-capilar-kerasys-oriental-premium-intensive-600ml\/","title":{"rendered":"SHAMPOO CAPILAR KERASYS ORIENTAL PREMIUM INTENSIVE 600ML"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/acdn-us.mitiendanube.com\/stores\/006\/567\/235\/themes\/common\/logo-2027072255-1755034523-ec9fa1f2ce585f2d0ef3c935b64032841755034523.png?0\" alt=\"Tienda Online de KERASYS\" width=\"130\" height=\"44\" \/><\/p>\n<h1>ORIENTAL PREMIUM INTENSIVE<\/h1>\n<p><span dir=\"auto\">El\u00a0<\/span><span dir=\"auto\">champ\u00fa<\/span><span dir=\"auto\">, enriquecido con\u00a0<\/span><span class=\"keywords\"><span dir=\"auto\">aceite de camelia roja<\/span><\/span><span dir=\"auto\"> y prote\u00ednas vegetales, limpia con suavidad y fortalece la fibra capilar desde la ra\u00edz.\u00a0 <\/span><span dir=\"auto\">Ideal para restaurar la vitalidad del cabello despu\u00e9s de tratamientos qu\u00edmicos, exposici\u00f3n solar o herramientas de peinado con calor, este kit restaura la suavidad y la fuerza natural del cabello, manteni\u00e9ndolo ligero y saludable.<\/span><\/p>\n<h2><span dir=\"auto\">Beneficios clave<\/span><\/h2>\n<p><span dir=\"auto\">\u2022 Nutrici\u00f3n intensiva con aceite de camelia y prote\u00ednas vegetales<\/span><br \/>\n<span dir=\"auto\">\u2022 Fortalecimiento y reparaci\u00f3n de la fibra capilar<\/span><br \/>\n<span dir=\"auto\">\u2022 Brillo de espejo y tacto sedoso<\/span><br \/>\n<span dir=\"auto\">\u2022 Control del encrespamiento y manejabilidad<\/span><br \/>\n<span dir=\"auto\">\u2022 Protecci\u00f3n contra la sequedad y los da\u00f1os externos<\/span><\/p>\n<h2><span dir=\"auto\">Instrucciones de uso<\/span><\/h2>\n<p><span dir=\"auto\">Aplique el champ\u00fa sobre el cabello mojado, masajee hasta formar espuma y enjuague bien. Repita si es necesario. Luego, aplique el acondicionador de medios a puntas, evitando las ra\u00edces. Deje actuar unos minutos y enjuague bien. Para obtener mejores resultados, \u00faselo a diario.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ORIENTAL PREMIUM INTENSIVE El\u00a0champ\u00fa, enriquecido con\u00a0aceite de camelia roja y prote\u00ednas vegetales, limpia con suavidad y fortalece la fibra capilar<\/p>\n","protected":false},"featured_media":97740,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[204],"product_cat":[85],"product_tag":[2705],"class_list":{"0":"post-97739","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kerasys","7":"product_cat-cosmeticos","8":"product_tag-2705","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/comments?post=97739"}],"version-history":[{"count":1,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97739\/revisions"}],"predecessor-version":[{"id":97742,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97739\/revisions\/97742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media\/97740"}],"wp:attachment":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media?parent=97739"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_brand?post=97739"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_cat?post=97739"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_tag?post=97739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}