{"id":97770,"date":"2026-02-07T14:49:12","date_gmt":"2026-02-07T14:49:12","guid":{"rendered":"https:\/\/brandss.com.py\/index\/?post_type=product&#038;p=97770"},"modified":"2026-02-07T14:49:38","modified_gmt":"2026-02-07T14:49:38","slug":"shampoo-capilar-kerasys-royal-propolis-green-1000ml","status":"publish","type":"product","link":"https:\/\/brandss.com.py\/index\/producto\/shampoo-capilar-kerasys-royal-propolis-green-1000ml\/","title":{"rendered":"SHAMPOO CAPILAR KERASYS ROYAL PROPOLIS GREEN 1000ML"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/acdn-us.mitiendanube.com\/stores\/006\/567\/235\/themes\/common\/logo-2027072255-1755034523-ec9fa1f2ce585f2d0ef3c935b64032841755034523.png?0\" alt=\"Tienda Online de KERASYS\" width=\"130\" height=\"44\" \/><\/p>\n<h1>ROYAL PROPOLIS GREEN<\/h1>\n<p data-start=\"235\" data-end=\"294\"><em><strong data-start=\"238\" data-end=\"294\">Revitaliza tu cabello con la fuerza de la naturaleza<\/strong><\/em><\/p>\n<p data-start=\"296\" data-end=\"569\">Descubre Royal Propolis Green, un shampoo formulado para transformar tu rutina capilar con una mezcla \u00fanica de extractos naturales, prop\u00f3leos nutritivos y una fragancia refrescante. Ideal para quienes buscan un cuidado profundo, equilibrado y diario.<\/p>\n<h3 data-start=\"571\" data-end=\"593\"><strong data-start=\"573\" data-end=\"593\">Beneficios clave<\/strong><\/h3>\n<ul data-start=\"594\" data-end=\"1315\">\n<li data-start=\"594\" data-end=\"743\">\n<p data-start=\"596\" data-end=\"743\"><strong data-start=\"596\" data-end=\"629\">Limpieza profunda y delicada:<\/strong> Su f\u00f3rmula elimina suavemente impurezas, exceso de grasa y residuos sin resecar el cabello ni el cuero cabelludo.<\/p>\n<\/li>\n<li data-start=\"744\" data-end=\"925\">\n<p data-start=\"746\" data-end=\"925\"><strong data-start=\"746\" data-end=\"781\">Acci\u00f3n nutritiva con prop\u00f3leos:<\/strong> Enriquecido con prop\u00f3leos de origen natural, este shampoo ayuda a fortalecer la fibra capilar desde la ra\u00edz, aportando vitalidad y resistencia.<\/p>\n<\/li>\n<li data-start=\"926\" data-end=\"1087\">\n<p data-start=\"928\" data-end=\"1087\"><strong data-start=\"928\" data-end=\"954\">Equilibrio y frescura:<\/strong> Ideal para todo tipo de cabello, especialmente para quienes desean un efecto limpiador saludable con sensaci\u00f3n de frescura duradera.<\/p>\n<\/li>\n<li data-start=\"1088\" data-end=\"1205\">\n<p data-start=\"1090\" data-end=\"1205\"><strong data-start=\"1090\" data-end=\"1112\">Brillo y suavidad:<\/strong> Deja el cabello suave, manejable y con un brillo natural que se nota en cada movimiento.<\/p>\n<\/li>\n<li data-start=\"1206\" data-end=\"1315\">\n<p data-start=\"1208\" data-end=\"1315\"><strong data-start=\"1208\" data-end=\"1236\">Fragancia revitalizante:<\/strong> Su aroma herbal y fresco convierte tu ba\u00f1o en una experiencia sensorial \u00fanica.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1317\" data-end=\"1561\"><strong data-start=\"1320\" data-end=\"1346\">Textura y presentaci\u00f3n<\/strong><\/h3>\n<p data-start=\"1317\" data-end=\"1561\">\nPresentado en un envase generoso de 1000 ml, Royal Propolis Green es perfecto tanto para uso familiar como profesional. Su textura cremosa facilita la aplicaci\u00f3n y consigue espuma abundante desde el primer uso.<\/p>\n<p data-start=\"1568\" data-end=\"1704\"><strong data-start=\"1571\" data-end=\"1586\">Ideal para:<\/strong> Cabello normal a graso, personas que buscan una limpieza equilibrada y un cuidado natural con ingredientes bot\u00e1nicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROYAL PROPOLIS GREEN Revitaliza tu cabello con la fuerza de la naturaleza Descubre Royal Propolis Green, un shampoo formulado para<\/p>\n","protected":false},"featured_media":97771,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[204],"product_cat":[85],"product_tag":[2711],"class_list":{"0":"post-97770","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kerasys","7":"product_cat-cosmeticos","8":"product_tag-2711","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/comments?post=97770"}],"version-history":[{"count":1,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97770\/revisions"}],"predecessor-version":[{"id":97774,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product\/97770\/revisions\/97774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media\/97771"}],"wp:attachment":[{"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/media?parent=97770"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_brand?post=97770"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_cat?post=97770"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/brandss.com.py\/index\/wp-json\/wp\/v2\/product_tag?post=97770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}